{"id":6024,"date":"2025-10-17T09:05:37","date_gmt":"2025-10-17T07:05:37","guid":{"rendered":"https:\/\/www.cambrapropietatgirona.com\/els-governs-de-catalunya-i-del-pais-basc-uneixen-forces-per-demanar-a-la-unio-europea-fons-permanents-que-aportin-solucions-a-la-crisi-dhabitatge-de-les-dues-comunitats-autonomes\/"},"modified":"2025-10-17T09:08:53","modified_gmt":"2025-10-17T07:08:53","slug":"los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas","status":"publish","type":"post","link":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/","title":{"rendered":"Los gobiernos de Catalunya y del Pa\u00eds Vasco unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisis de vivienda de ambas comunidades aut\u00f3nomas"},"content":{"rendered":"<h2>Catalunya y Euskadi quieren responder conjuntamente a las crecientes dificultades de acceso a la vivienda.<\/h2>\n<p>La consejera de Territorio, Vivienda y Transici\u00f3n Ecol\u00f3gica de la Generalitat, S\u00edlvia Paneque, ha asegurado que \u201ces imprescindible mantener las inversiones en vivienda de manera permanente en los pr\u00f3ximos a\u00f1os y con fondos suficientes para apoyar la ampliaci\u00f3n de los parques de vivienda p\u00fablica de alquiler asequible\u201d.<\/p>\n<p>En la misma l\u00ednea, el consejero de Vivienda y Agenda Urbana del gobierno vasco, Denis Itxaso, ha afirmado que \u201cEuropa se juega su futuro en buena medida con este plan de vivienda asequible\u201d.<\/p>\n<p><strong>Con estas declaraciones, ambos gobiernos defienden la necesidad de una arquitectura financiera europea estable que permita financiar un nuevo parque de vivienda asequible y reducir las desigualdades territoriales.<\/strong><\/p>\n<h4><strong>\u00bfPor qu\u00e9 son necesarios estos fondos? <\/strong><\/h4>\n<p>Para cumplir con el <em>Pla Territorial Sectorial d\u2019Habitatge 2024<\/em>, Catalunya se ha fijado como objetivo que, en un plazo de 20 a\u00f1os, el 15 % del parque de viviendas se destine a pol\u00edticas sociales. A su vez, Euskadi se ha establecido dos metas: alcanzar un parque p\u00fablico de alquiler asequible que represente el 5 % de las viviendas principales antes de 2036 y garantizar una reserva permanente de vivienda protegida que llegue al 12 % del total.<\/p>\n<h4><strong>Se han propuesto 10 iniciativas<\/strong><\/h4>\n<ol>\n<li>La vivienda como pilar del bienestar colectivo. Reclaman que la vivienda sea una prioridad en la agenda social europea.<\/li>\n<li>Impulso de una pol\u00edtica de vivienda estructural. Quieren mantener una pol\u00edtica de vivienda que perdure en el tiempo, ya que consideran que son las que aportan buenos resultados.<\/li>\n<li>Convergencia territorial y cohesi\u00f3n social. Proponen establecer criterios comunes para medir y evaluar las pol\u00edticas de vivienda, con objetivos calendarizados. Destacan que el pa\u00eds est\u00e1 muy por debajo de la media europea en vivienda social e inversi\u00f3n.<\/li>\n<li>Marco flexible para el urbanismo, el suelo y la vivienda. Europa necesita un marco flexible que permita a los estados y comunidades desarrollar pol\u00edticas adaptadas al territorio y a diferentes escalas.<\/li>\n<li>Fondos permanentes para apoyar la construcci\u00f3n de vivienda asequible. Reclaman un marco europeo que d\u00e9 margen a los estados, regiones y municipios para aplicar pol\u00edticas de vivienda adaptadas a sus realidades.<\/li>\n<li>Mecanismos de financiaci\u00f3n a largo plazo y bajo inter\u00e9s para favorecer la construcci\u00f3n de vivienda asequible.<\/li>\n<li>Inversi\u00f3n en vivienda asequible fuera de la regla de gasto. Las inversiones p\u00fablicas en vivienda asequible deben considerarse fuera del balance presupuestario.<\/li>\n<li>Priorizar la funci\u00f3n social de la vivienda frente a la especulaci\u00f3n.<\/li>\n<li>Equilibrio territorial y lucha contra la despoblaci\u00f3n. Proponen fomentar la vivienda en \u00e1reas rurales.<\/li>\n<li>Juventud y emancipaci\u00f3n en el centro de las pol\u00edticas p\u00fablicas de vivienda. Promover que los j\u00f3venes puedan acceder a una vivienda.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Catalunya y Euskadi quieren responder conjuntamente a las crecientes dificultades de acceso a la vivienda. La consejera de Territorio, Vivienda y Transici\u00f3n Ecol\u00f3gica de la Generalitat, S\u00edlvia Paneque, ha asegurado que \u201ces imprescindible mantener las inversiones en vivienda de manera permanente en los pr\u00f3ximos a\u00f1os y con fondos suficientes para apoyar la ampliaci\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"disable_featured_image":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-6024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona<\/title>\n<meta name=\"description\" content=\"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"og:description\" content=\"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T07:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T07:08:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AE5GBNi67xK1QkS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AE5GBNi67xK1QkS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/\"},\"author\":{\"name\":\"AE5GBNi67xK1QkS\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\"},\"headline\":\"Los gobiernos de Catalunya y del Pa\u00eds Vasco unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisis de vivienda de ambas comunidades aut\u00f3nomas\",\"datePublished\":\"2025-10-17T07:05:37+00:00\",\"dateModified\":\"2025-10-17T07:08:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/17_10_newsletter.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/\",\"name\":\"Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/17_10_newsletter.jpg\",\"datePublished\":\"2025-10-17T07:05:37+00:00\",\"dateModified\":\"2025-10-17T07:08:53+00:00\",\"description\":\"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/17_10_newsletter.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/17_10_newsletter.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"Catalunya i Euskadi volen respondre conjuntament a les dificultats creixents d\u2019acc\u00e9s a l\u2019habitatge.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los gobiernos de Catalunya y del Pa\u00eds Vasco unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisis de vivienda de ambas comunidades aut\u00f3nomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"description\":\"Serveis immobiliaris integrals als propietaris\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"width\":277,\"height\":269,\"caption\":\"Cambra de la Propietat Urbana de Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\",\"name\":\"AE5GBNi67xK1QkS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"caption\":\"AE5GBNi67xK1QkS\"},\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/author\\\/ae5gbni67xk1qks\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona","description":"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/","og_locale":"es_ES","og_type":"article","og_title":"Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona","og_description":"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.","og_url":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/","og_site_name":"Cambra de la Propietat Urbana de Girona","article_published_time":"2025-10-17T07:05:37+00:00","article_modified_time":"2025-10-17T07:08:53+00:00","og_image":[{"width":1080,"height":1350,"url":"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg","type":"image\/jpeg"}],"author":"AE5GBNi67xK1QkS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"AE5GBNi67xK1QkS","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#article","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/"},"author":{"name":"AE5GBNi67xK1QkS","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c"},"headline":"Los gobiernos de Catalunya y del Pa\u00eds Vasco unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisis de vivienda de ambas comunidades aut\u00f3nomas","datePublished":"2025-10-17T07:05:37+00:00","dateModified":"2025-10-17T07:08:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg","articleSection":["Actualidad"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/","url":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/","name":"Catalunya y Euskadi piden fondos que disminuyan la crisi de la vivienda - Cambra de la Propietat Urbana de Girona","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#primaryimage"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg","datePublished":"2025-10-17T07:05:37+00:00","dateModified":"2025-10-17T07:08:53+00:00","description":"Catalunya y Euskadi unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisi de la vivienda.","breadcrumb":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#primaryimage","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/17_10_newsletter.jpg","width":1080,"height":1350,"caption":"Catalunya i Euskadi volen respondre conjuntament a les dificultats creixents d\u2019acc\u00e9s a l\u2019habitatge."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/los-gobiernos-de-catalunya-y-del-pais-vasco-unen-fuerzas-para-pedir-a-la-union-europea-fondos-permanentes-que-aporten-soluciones-a-la-crisis-de-vivienda-de-ambas-comunidades-autonomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cambrapropietatgirona.com\/"},{"@type":"ListItem","position":2,"name":"Los gobiernos de Catalunya y del Pa\u00eds Vasco unen fuerzas para pedir a la Uni\u00f3n Europea fondos permanentes que aporten soluciones a la crisis de vivienda de ambas comunidades aut\u00f3nomas"}]},{"@type":"WebSite","@id":"https:\/\/www.cambrapropietatgirona.com\/#website","url":"https:\/\/www.cambrapropietatgirona.com\/","name":"Cambra de la Propietat Urbana de Girona","description":"Serveis immobiliaris integrals als propietaris","publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambrapropietatgirona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.cambrapropietatgirona.com\/#organization","name":"Cambra de la Propietat Urbana de Girona","url":"https:\/\/www.cambrapropietatgirona.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","width":277,"height":269,"caption":"Cambra de la Propietat Urbana de Girona"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c","name":"AE5GBNi67xK1QkS","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","caption":"AE5GBNi67xK1QkS"},"url":"https:\/\/www.cambrapropietatgirona.com\/es\/author\/ae5gbni67xk1qks\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/comments?post=6024"}],"version-history":[{"count":2,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6024\/revisions"}],"predecessor-version":[{"id":6026,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6024\/revisions\/6026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media\/6021"}],"wp:attachment":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media?parent=6024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/categories?post=6024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/tags?post=6024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}