{"id":6016,"date":"2025-10-06T12:21:32","date_gmt":"2025-10-06T10:21:32","guid":{"rendered":"https:\/\/www.cambrapropietatgirona.com\/lagrupacio-daquarellistes-de-girona-exposa-20-obres-de-diferents-autors-durant-lexposicio-fires-de-girona\/"},"modified":"2025-10-06T12:22:45","modified_gmt":"2025-10-06T10:22:45","slug":"lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona","status":"publish","type":"post","link":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/","title":{"rendered":"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona Girona expone 20 obras de diferentes autores durante la Exposici\u00f3n de Fires de Girona"},"content":{"rendered":"<h2><strong>La Cambra de la Propietat Urbana de Girona te invita a visitar la exposici\u00f3n <em>\u201cFires\u201925\u201d<\/em>, una muestra colectiva de los socios de la Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona.<\/strong><\/h2>\n<p>La exposici\u00f3n se podr\u00e1 visitar en la sede de la Cambra, en la calle Ciutadans, 12, de Girona, hasta el 30 de octubre. Estar\u00e1 abierta al p\u00fablico de lunes a viernes, de 17 a 20 h, y los fines de semana, de 10 a 13 h y de 17 a 19 h.<\/p>\n<p>Se trata de una selecci\u00f3n de 20 obras de tem\u00e1tica libre, pintadas en acuarela especialmente para esta ocasi\u00f3n. Los diferentes autores que participan son artistas reconocidos en el \u00e1mbito art\u00edstico y miembros activos de la agrupaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6011\" src=\"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/cambra-300x300.jpg\" alt=\"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona exposa 20 obres de diferents autors durant l\u2019Exposici\u00f3 Fires de Girona\" width=\"433\" height=\"433\" srcset=\"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/cambra-300x300.jpg 300w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/cambra-150x150.jpg 150w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/cambra-87x87.jpg 87w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/cambra.jpg 640w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/p>\n<h4><strong>Sobre la Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona<\/strong><\/h4>\n<p>La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona es una entidad sin \u00e1nimo de lucro creada en el a\u00f1o 1992 con el objetivo de promocionar y divulgar el arte de la acuarela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cambra de la Propietat Urbana de Girona te invita a visitar la exposici\u00f3n \u201cFires\u201925\u201d, una muestra colectiva de los socios de la Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona. La exposici\u00f3n se podr\u00e1 visitar en la sede de la Cambra, en la calle Ciutadans, 12, de Girona, hasta el 30 de octubre. Estar\u00e1 abierta al p\u00fablico de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"disable_featured_image":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-6016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona<\/title>\n<meta name=\"description\" content=\"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"og:description\" content=\"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-06T10:21:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T10:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AE5GBNi67xK1QkS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AE5GBNi67xK1QkS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/\"},\"author\":{\"name\":\"AE5GBNi67xK1QkS\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\"},\"headline\":\"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona Girona expone 20 obras de diferentes autores durante la Exposici\u00f3n de Fires de Girona\",\"datePublished\":\"2025-10-06T10:21:32+00:00\",\"dateModified\":\"2025-10-06T10:22:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/portada.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/\",\"name\":\"La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/portada.jpg\",\"datePublished\":\"2025-10-06T10:21:32+00:00\",\"dateModified\":\"2025-10-06T10:22:45+00:00\",\"description\":\"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/portada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/portada.jpg\",\"width\":640,\"height\":640,\"caption\":\"Exposici\u00f3 Fires de Girona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona Girona expone 20 obras de diferentes autores durante la Exposici\u00f3n de Fires de Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"description\":\"Serveis immobiliaris integrals als propietaris\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"width\":277,\"height\":269,\"caption\":\"Cambra de la Propietat Urbana de Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\",\"name\":\"AE5GBNi67xK1QkS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"caption\":\"AE5GBNi67xK1QkS\"},\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/author\\\/ae5gbni67xk1qks\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona","description":"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/","og_locale":"es_ES","og_type":"article","og_title":"La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona","og_description":"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona","og_url":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/","og_site_name":"Cambra de la Propietat Urbana de Girona","article_published_time":"2025-10-06T10:21:32+00:00","article_modified_time":"2025-10-06T10:22:45+00:00","og_image":[{"width":640,"height":640,"url":"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg","type":"image\/jpeg"}],"author":"AE5GBNi67xK1QkS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"AE5GBNi67xK1QkS","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#article","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/"},"author":{"name":"AE5GBNi67xK1QkS","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c"},"headline":"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona Girona expone 20 obras de diferentes autores durante la Exposici\u00f3n de Fires de Girona","datePublished":"2025-10-06T10:21:32+00:00","dateModified":"2025-10-06T10:22:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg","articleSection":["Actualidad"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/","url":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/","name":"La Agrupaci\u00f3 d\u2019Aquarel\u00b7listes presenta la Exposici\u00f3n Fires de Girona - Cambra de la Propietat Urbana de Girona","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#primaryimage"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg","datePublished":"2025-10-06T10:21:32+00:00","dateModified":"2025-10-06T10:22:45+00:00","description":"Te invitamos a visitar l\u2019exposici\u00f3 \u201cFires\u201925\u201d, una mostra col\u00b7lectiva dels socis de l\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona","breadcrumb":{"@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#primaryimage","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2025\/10\/portada.jpg","width":640,"height":640,"caption":"Exposici\u00f3 Fires de Girona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambrapropietatgirona.com\/es\/lagrupacio-daquarellistes-de-girona-girona-expone-20-obras-de-diferentes-autores-durante-la-exposicion-de-fires-de-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cambrapropietatgirona.com\/"},{"@type":"ListItem","position":2,"name":"L\u2019Agrupaci\u00f3 d\u2019Aquarel\u00b7listes de Girona Girona expone 20 obras de diferentes autores durante la Exposici\u00f3n de Fires de Girona"}]},{"@type":"WebSite","@id":"https:\/\/www.cambrapropietatgirona.com\/#website","url":"https:\/\/www.cambrapropietatgirona.com\/","name":"Cambra de la Propietat Urbana de Girona","description":"Serveis immobiliaris integrals als propietaris","publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambrapropietatgirona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.cambrapropietatgirona.com\/#organization","name":"Cambra de la Propietat Urbana de Girona","url":"https:\/\/www.cambrapropietatgirona.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","width":277,"height":269,"caption":"Cambra de la Propietat Urbana de Girona"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c","name":"AE5GBNi67xK1QkS","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","caption":"AE5GBNi67xK1QkS"},"url":"https:\/\/www.cambrapropietatgirona.com\/es\/author\/ae5gbni67xk1qks\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/comments?post=6016"}],"version-history":[{"count":1,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6016\/revisions"}],"predecessor-version":[{"id":6017,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/6016\/revisions\/6017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media\/6010"}],"wp:attachment":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media?parent=6016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/categories?post=6016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/tags?post=6016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}