{"id":5602,"date":"2025-01-01T12:23:52","date_gmt":"2025-01-01T11:23:52","guid":{"rendered":"https:\/\/www.cambrapropietatgirona.com\/?p=5602"},"modified":"2024-12-20T10:30:18","modified_gmt":"2024-12-20T09:30:18","slug":"exposicion-les-cares-dels-colors-de-ezequiel-casamada","status":"publish","type":"post","link":"https:\/\/www.cambrapropietatgirona.com\/es\/exposicion-les-cares-dels-colors-de-ezequiel-casamada\/","title":{"rendered":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada"},"content":{"rendered":"<h2>Te invitamos a visitar la exposici\u00f3n <strong>\u201cLes cares dels colors\u201d<\/strong>, donde se presentar\u00e1n las obras de Ezequiel Casamada.<\/h2>\n<p>La inauguraci\u00f3n de esta exposici\u00f3n tendr\u00e1 lugar este viernes 3 de enero a las 19 h, y se podr\u00e1 visitar en la sede de la C\u00e1mara, en la calle Ciutadans, 12, de Girona, del 3 de enero al 3 de febrero, de lunes a viernes de 16 h a 19 h. Esta exhibici\u00f3n est\u00e1 organizada por los Amigos del Museo de Arte de Girona.<\/p>\n<h4><strong>Sobre el pintor <\/strong><\/h4>\n<p>Ezequiel Casamada, nacido en Sabadell, entra en el mundo de la pintura buscando una manera de construir desde la nada. Procede del \u00e1mbito musical, es cantante cl\u00e1sico de profesi\u00f3n y desde hace a\u00f1os compagina estas dos facetas. Su primera exposici\u00f3n tuvo lugar en 2003 en la galer\u00eda Punt d\u2019Art de Girona. Desde entonces, ha participado en diversas exhibiciones. Entre las m\u00e1s destacadas se encuentran una colectiva en 2008 en el Fondo de Arte de Olot, una individual en 2011 en el Colegio de m\u00e9dicos de Madrid, otra individual en 2012 en el Parlamento Europeo en Bruselas (B\u00e9lgica), su participaci\u00f3n en la feria de arte contempor\u00e1neo \u201cArt shopping\u201d del Louvre en Par\u00eds (Francia) en 2015, y ese mismo a\u00f1o, una colectiva en la galer\u00eda \u201cArt cuestion\u201d en Ourense (Galicia). En 2021 realiz\u00f3 una exposici\u00f3n individual en el Palau Dalmases con motivo de la inauguraci\u00f3n de un espacio-galer\u00eda de arte. Cabe destacar la publicaci\u00f3n de algunos de sus cuadros en 2011 en la revista cultural alemana <em>Experimenta<\/em> y en la portada de la revista \u201cCiencia y Humanidades\u201d de la Fundaci\u00f3n Ram\u00f3n Areces de Madrid.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>&#8220;Me gustan los colores y las texturas, estos son los protagonistas de mi obra. Llena de manchas y trazos, mis telas suelen ser de formato medio, creadas con diferentes tipos de pinturas, medios y aditivos que generan, podr\u00edamos decir, un desorden inicial. Una vez alcanzado este objetivo, ordenamos ese caos, y poco a poco van surgiendo formas m\u00e1s cercanas: personajes, situaciones (inquietudes y denuncias, al fin y al cabo). As\u00ed es mi pintura.<\/p>\n<p>Seguramente, mi dedicaci\u00f3n y amor por las artes esc\u00e9nicas me lleva a pintar inconscientemente estos personajes, como si fueran actores de alguna historia inventada o no. Si nos acercamos, solo veremos manchas, pero a cierta distancia se revelan los contenidos del cuadro; como una met\u00e1fora propiamente dicha.<br \/>\nEn esta exposici\u00f3n veremos una recopilaci\u00f3n de las obras realizadas en los \u00faltimos a\u00f1os.\u201d<br \/>\nEzequiel Casamada<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-5596 \" src=\"http:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-738x1024.jpg\" alt=\"Exposici\u00f3 \u201cLes cares dels colors\u201d d\u2019Ezequiel Casamada\" width=\"563\" height=\"781\" srcset=\"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-738x1024.jpg 738w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-216x300.jpg 216w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-768x1065.jpg 768w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-1107x1536.jpg 1107w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-1476x2048.jpg 1476w, https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/Cartell_Ezequiel-1_241219_123448-scaled.jpg 1846w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te invitamos a visitar la exposici\u00f3n \u201cLes cares dels colors\u201d, donde se presentar\u00e1n las obras de Ezequiel Casamada. La inauguraci\u00f3n de esta exposici\u00f3n tendr\u00e1 lugar este viernes 3 de enero a las 19 h, y se podr\u00e1 visitar en la sede de la C\u00e1mara, en la calle Ciutadans, 12, de Girona, del 3 de enero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"disable_featured_image":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-5602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona<\/title>\n<meta name=\"description\" content=\"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\/Ciutadans, 12, Girona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"og:description\" content=\"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\/Ciutadans, 12, Girona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/\" \/>\n<meta property=\"og:site_name\" content=\"Cambra de la Propietat Urbana de Girona\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-01T11:23:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AE5GBNi67xK1QkS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AE5GBNi67xK1QkS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/\"},\"author\":{\"name\":\"AE5GBNi67xK1QkS\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\"},\"headline\":\"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada\",\"datePublished\":\"2025-01-01T11:23:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/\"},\"wordCount\":434,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cares-dels-colors.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/\",\"name\":\"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cares-dels-colors.jpg\",\"datePublished\":\"2025-01-01T11:23:52+00:00\",\"description\":\"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\\\/Ciutadans, 12, Girona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cares-dels-colors.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cares-dels-colors.jpg\",\"width\":640,\"height\":640,\"caption\":\"Exposici\u00f3 \u201cLes cares dels colors\u201d d\u2019Ezequiel Casamada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/exposicio-les-cares-dels-colors-dezequiel-casamada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"description\":\"Serveis immobiliaris integrals als propietaris\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#organization\",\"name\":\"Cambra de la Propietat Urbana de Girona\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/favicon.jpg\",\"width\":277,\"height\":269,\"caption\":\"Cambra de la Propietat Urbana de Girona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/#\\\/schema\\\/person\\\/839c74db646ec3d6738ce2dcf5b3447c\",\"name\":\"AE5GBNi67xK1QkS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g\",\"caption\":\"AE5GBNi67xK1QkS\"},\"url\":\"https:\\\/\\\/www.cambrapropietatgirona.com\\\/es\\\/author\\\/ae5gbni67xk1qks\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona","description":"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\/Ciutadans, 12, Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona","og_description":"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\/Ciutadans, 12, Girona","og_url":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/","og_site_name":"Cambra de la Propietat Urbana de Girona","article_published_time":"2025-01-01T11:23:52+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg","type":"image\/jpeg"}],"author":"AE5GBNi67xK1QkS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"AE5GBNi67xK1QkS","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#article","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/"},"author":{"name":"AE5GBNi67xK1QkS","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c"},"headline":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada","datePublished":"2025-01-01T11:23:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/"},"wordCount":434,"commentCount":0,"publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg","articleSection":["Actualidad"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/","url":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/","name":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada - Cambra de la Propietat Urbana de Girona","isPartOf":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#primaryimage"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg","datePublished":"2025-01-01T11:23:52+00:00","description":"Visita l\u2019Exposici\u00f3 \u201cLes cares dels colors\u201d, amb les obres d\u2019Ezequiel Casamada, del 3 de gener al 3 febrer al c\/Ciutadans, 12, Girona","breadcrumb":{"@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#primaryimage","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2024\/12\/cares-dels-colors.jpg","width":640,"height":640,"caption":"Exposici\u00f3 \u201cLes cares dels colors\u201d d\u2019Ezequiel Casamada"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cambrapropietatgirona.com\/exposicio-les-cares-dels-colors-dezequiel-casamada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cambrapropietatgirona.com\/"},{"@type":"ListItem","position":2,"name":"Exposici\u00f3n \u201cLes cares dels colors\u201d de Ezequiel Casamada"}]},{"@type":"WebSite","@id":"https:\/\/www.cambrapropietatgirona.com\/#website","url":"https:\/\/www.cambrapropietatgirona.com\/","name":"Cambra de la Propietat Urbana de Girona","description":"Serveis immobiliaris integrals als propietaris","publisher":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cambrapropietatgirona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.cambrapropietatgirona.com\/#organization","name":"Cambra de la Propietat Urbana de Girona","url":"https:\/\/www.cambrapropietatgirona.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","contentUrl":"https:\/\/www.cambrapropietatgirona.com\/wp-content\/uploads\/2018\/01\/favicon.jpg","width":277,"height":269,"caption":"Cambra de la Propietat Urbana de Girona"},"image":{"@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cambrapropietatgirona.com\/#\/schema\/person\/839c74db646ec3d6738ce2dcf5b3447c","name":"AE5GBNi67xK1QkS","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a49b57693d82ed8aed27ea81234f80da517724ec1cc1f1fb4952b6cf4b80fd7?s=96&d=mm&r=g","caption":"AE5GBNi67xK1QkS"},"url":"https:\/\/www.cambrapropietatgirona.com\/es\/author\/ae5gbni67xk1qks\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/5602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/comments?post=5602"}],"version-history":[{"count":2,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/5602\/revisions"}],"predecessor-version":[{"id":5604,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/posts\/5602\/revisions\/5604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media\/5595"}],"wp:attachment":[{"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/media?parent=5602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/categories?post=5602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cambrapropietatgirona.com\/es\/wp-json\/wp\/v2\/tags?post=5602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}